{"id":55369,"date":"2021-05-17T10:45:35","date_gmt":"2021-05-17T08:45:35","guid":{"rendered":"https:\/\/www.pcspezialist.de\/blog\/?p=55369"},"modified":"2024-11-05T08:46:22","modified_gmt":"2024-11-05T07:46:22","slug":"whatsapp-neue-nutzungsbedingungen","status":"publish","type":"post","link":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/","title":{"rendered":"WhatsApp neue Nutzungsbedingungen ## Konzern rudert erneut zur\u00fcck: keine Accountl\u00f6schung"},"content":{"rendered":"<p><strong>Bereits im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt und Nutzer per Pop-up darum gebeten, dass sie den Nutzungsbedingungen 2021 zustimmen. Ziel der neuen Nutzungsbedingungen ist es, dass WhatsApp bestimmte Daten mit Facebook-Unternehmen und Facebook-Dienstleistern teilen kann.\u00a0<\/strong><\/p>\n<p>Was passiert, wenn man den Nutzungsbedingungen nicht zustimmt hat? Alle Infos dazu bei uns.<\/p>\n<p><!--more--><\/p>\n<div style=\"background: #f2f2f2; padding: 15px 15px 5px; margin: 30px 0;\">\n<p><strong>Unser Beitrag \u00fcber die neuen WhatsApp-Nutzungsbedingungen im \u00dcberblick:\u00a0<\/strong><\/p>\n<ol style=\"line-height: 1.7;\">\n<li><a href=\"#eins\">WhatsApp neue Nutzungsbedingungen \u2013 was ist neu?<\/a><\/li>\n<li><a href=\"#zwei\">WhatsApp neue Nutzungsbedingungen ab Mai<\/a><\/li>\n<li><a href=\"#drei\">Nutzungsbedingungen 2021 \u2013 WhatsApp rudert zur\u00fcck<\/a><\/li>\n<li><a href=\"#vier\">Warum pocht WhatsApp auf Zustimmung?<\/a>\n<ul style=\"line-height: 1.7;\">\n<li><a href=\"#fuenf\">Gewinne durch Angebote f\u00fcr Firmen<\/a><\/li>\n<\/ul>\n<\/li>\n<li><a href=\"#sechs\">WhatsApp neue Nutzungsbedingungen ablehnen<\/a><\/li>\n<li><a href=\"#sieben\">Update vom 01.06.2021: Erneute Rolle r\u00fcckw\u00e4rts<\/a><\/li>\n<li><a href=\"#acht\">Update vom 30.08.2021: Nutzungsbedingungen optional<\/a><\/li>\n<\/ol>\n<\/div>\n<h3 id=\"eins\">WhatsApp neue Nutzungsbedingungen \u2013 was ist neu?<\/h3>\n<p>Zu Beginn dieses Jahres setzte WhatsApp all seinen Nutzern eine recht kurze Frist: Bis zum 8. Februar m\u00fcssen alle Nutzer den <strong>neuen Nutzungsbedingungen<\/strong> zustimmen. Eine Nichtzustimmung h\u00e4tte zur Folge, dass User WhatsApp nicht mehr verwenden k\u00f6nnten. WhatsApp Inc. wollte <strong>WhatsApp f\u00fcr Verweigerer abschalten<\/strong>. Der Aufschrei war gro\u00df und die massenhafte Abwanderung zu <a href=\"https:\/\/pcspezialist.de\/blog\/2021\/01\/15\/whatsapp-alternative\/\">alternativen Messengern<\/a>, wie beispielsweise <a href=\"https:\/\/pcspezialist.de\/blog\/2021\/01\/18\/telegram-messenger\/\">Telegram<\/a> begann.<\/p>\n<p>Schlie\u00dflich hatte WhatsApp mit den neuen Nutzungsbedingungen etwas beschlossen, was Mutterkonzern Facebook 2014 noch kategorisch ausgeschlossen hatte: Das Teilen von Daten mit Facebook-Unternehmen und anderen Werbepartnern. F\u00fcr viele User war das ein Grund, WhatsApp den R\u00fccken zu kehren. Und der Konzern reagierte auf den Unmut seiner Nutzer, WhatsApp neue Nutzungsbedingungen wurden erst einmal nicht eingef\u00fchrt.<\/p>\n<p>Stattdessen wurden die Frist zur <strong>Zustimmung auf den 15. Mai 2021 verschoben<\/strong>. Wer bis dahin dem immer wieder auftauchenden Pop-up nicht zugestimmt hatte, sollte WhatsApp ab diesem Datum nicht mehr nutzen k\u00f6nnen. Und nun? Seit vergangenen Sonnabend gelten die Nutzungsbedingungen 2021 \u2013 oder etwa doch nicht?<\/p>\n<div id=\"attachment_55392\" style=\"width: 650px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-55392\" class=\"size-full wp-image-55392\" src=\"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/adem-ay-ik_AuIWeBBM-unsplash.jpg\" alt=\"Handy-Display mit verschiedenen Messengern. Bild: Unsplash\/Adem AY\" width=\"640\" height=\"427\" \/><p id=\"caption-attachment-55392\" class=\"wp-caption-text\">Ab wann gelten die neuen Nutzungsbedingungen? Bild: Unsplash\/Adem AY<\/p><\/div>\n<h3 id=\"zwei\">WhatsApp neue Nutzungsbedingungen ab Mai<\/h3>\n<p>Der WhatsApp-Plan war ein ganz einfacher. Wer den Nutzungsbedingungen nicht zustimmt, wer also die <strong>Datenweitergabe an Facebook-Unternehmen und Werbepartnern verweigert<\/strong>, muss ab 15. Mai mit <strong>Einschr\u00e4nkungen<\/strong> rechnen. Und wie sehen die aus? In den FAQs findet sich die Antwort: \u201eDu wirst zwar f\u00fcr kurze Zeit Anrufe und Benachrichtigungen erhalten, aber in der App weder Nachrichten lesen noch welche senden k\u00f6nnen.\u201c\u00a0Die genannte \u201ekurze Zeit\u201c ist eine Dauer von 120 Tagen. Danach will WhatsApp die Accounts der Verweigerer l\u00f6schen.<\/p>\n<p>Konkret bedeutet das, dass Accounts der Nichtzustimmenden ab dem 15. Mai nur noch \u00e4u\u00dferst eingeschr\u00e4nkt genutzt werden k\u00f6nnen. Sie k\u00f6nnen noch 120 Tage lang Anrufe erhalten und annehmen, sowie, wenn aktiviert, die Benachrichtigungen \u00fcber eingehende Mitteilungen sehen und \u00fcber den Sperrbildschirm beantworten. Auf die Chatliste gibt es keinen Zugriff mehr.<\/p>\n<h3 id=\"drei\">Nutzungsbedingungen 2021 \u2013 WhatsApp rudert zur\u00fcck<\/h3>\n<p>Dass WhatsApp neue Nutzungsbedingungen einf\u00fchrt, steht fest, die Frage ist nur, wann. Anscheinend hat WhatsApp erneut gro\u00dfe <strong>Sorge, dass zahlreiche Nutzer abwandern<\/strong>. Oder ist es anders erkl\u00e4rbar, dass WhatsApp erneut zur\u00fcckrudert und die <strong>Ank\u00fcndigungen zum 15. Mai nicht wahrgemacht<\/strong> hat? Nun hei\u00dft es, dass die Verweigerer der Nutzungsbedingungen ihre Accounts noch f\u00fcr 120 Tagen ganz normal nutzen k\u00f6nnen. Erst danach soll es Einschr\u00e4nkungen geben. Stichtag ist also nun der 12. September 2021.<\/p>\n<p>In den FAQs ist aktuell Folgendes zu lesen: \u201eEs werden aufgrund der Aktualisierung am 15. Mai weder Accounts gel\u00f6scht, noch die Funktionalit\u00e4t von WhatsApp eingeschr\u00e4nkt.\u201c Das bedeutet also, dass Sie WhatsApp weiterhin uneingeschr\u00e4nkt nutzen k\u00f6nnen, auch wenn Sie den Nutzungsbedingungen bislang nicht zugestimmt haben.<\/p>\n<p>Allerdings bekommen Sie dann auch <strong>weiterhin den Hinweis zu den WhatsApp Nutzungsbedingungen 2021<\/strong> angezeigt \u2013 mit dem Hinweis, sie zu akzeptieren. WhatsApp gibt also nicht auf uns versucht weiterhin, seine User dazu zu treiben, der Datenweitergabe zuzustimmen.<\/p>\n<div id=\"attachment_55393\" style=\"width: 650px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-55393\" class=\"size-full wp-image-55393\" src=\"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/tushar-mahajan-pRtogCbgh7M-unsplash.jpg\" alt=\"Zeitungsausschnitt zur WhatsApp-Privatsph\u00e4re. Bild: Unsplash\/Tushar Mahajan\" width=\"640\" height=\"480\" \/><p id=\"caption-attachment-55393\" class=\"wp-caption-text\">Auch wenn WhatsApp Daten weitergibt, betont es, dass die Privatsph\u00e4re erhalten bleibt. Bild: Unsplash\/Tushar Mahajan<\/p><\/div>\n<h3 id=\"vier\">Warum pocht WhatsApp auf Zustimmung?<\/h3>\n<p>Doch warum will Mutterkonzern Facebook f\u00fcr WhatsApp neue Nutzungsbedingungen? Der <strong>Hintergrund<\/strong> f\u00fcr die Datenschutz\u00e4nderung ist mal wieder das liebe <strong>Geld<\/strong>. Facebook hatte WhatsApp im Jahr 2014 f\u00fcr stolze 22 Milliarden Dollar \u00fcbernommen. Zu dem Zeitpunkt hie\u00df es, eine Daten\u00fcbernahme oder Weitergabe sei weder m\u00f6glich noch gewollt. Doch da Facebook seit jeder f\u00fcr seine <a href=\"https:\/\/pcspezialist.de\/blog\/2018\/06\/26\/datenkrake-facebook\/\">Datensammelwut<\/a> bekannt ist, war es nur eine Frage der Zeit, bis entweder Werbung und\/oder die Datenweitergabe ins Spiel gebracht wird.<\/p>\n<p>Die Frage der <strong>Werbung bei WhatsApp<\/strong> kommt immer mal wieder auf, denn dank Werbung k\u00f6nnte die App f\u00fcr Facebook endlich profitabel werden. So ist es kein Wunder, dass bereits im Jahr 2018 von der Einf\u00fchrung von <a href=\"https:\/\/pcspezialist.de\/blog\/2018\/05\/09\/whatsapp-werbung\/\">Werbung bei WhatsApp<\/a> die Rede war. Im Jahr 2020 folgte das \u00fcberraschende <a href=\"https:\/\/pcspezialist.de\/blog\/2020\/01\/20\/werbung-bei-whatsapp\/\">Werbe-Aus<\/a>. So kommt es, dass die App bis heute keinen Gewinn f\u00fcr Facebook einbringt.<\/p>\n<h4 id=\"fuenf\">Gewinne durch Angebote f\u00fcr Firmen<\/h4>\n<p>Das soll die <strong>Weitergabe der Daten an Facebook<\/strong> \u00e4ndern. Und die <a href=\"https:\/\/pcspezialist.de\/blog\/2016\/08\/31\/whatsapp-datenweitergabe-verhindern\/\">Datenweitergabe an Facebook<\/a> stand bereits im Jahr 2016 im Raum. Geplant ist jetzt eine <strong>Kommunikation mit Unternehmen<\/strong>: Die Nutzer des Dienstes k\u00f6nnen nach Facebooks Pl\u00e4nen k\u00fcnftig mit Firmen kommunizieren, um Fragen zu stellen, Eink\u00e4ufe zu t\u00e4tigen oder Informationen \u00fcber Bestellvorg\u00e4nge zu bekommen.<\/p>\n<p>So h\u00e4tten beispielsweise Fluggesellschaften oder Einzelh\u00e4ndler die M\u00f6glichkeit, WhatsApp in ihren Kundenservice einzubinden. Und f\u00fcr ein professionelles Angebot zahlen die Firmen Geb\u00fchren \u2013 und Facebook schl\u00e4gt endlich Gewinn aus der Messenger-App.<\/p>\n<p>Dabei betont WhatsApp, dass sich an den <strong>Privatsph\u00e4re-Einstellungen<\/strong> nichts \u00e4ndert. Auch an der <a href=\"https:\/\/pcspezialist.de\/blog\/2017\/01\/18\/whatsapp-sicherheit\/\">Ende-zu-Ende-Verschl\u00fcsselung<\/a> werde nicht ger\u00fcttelt \u2013 mit einer Einschr\u00e4nkung: \u201eWenn du mit einem Unternehmen \u00fcber Telefon, E-Mail oder WhatsApp kommunizierst, kann es die Informationen aus diesen Interaktionen mit dir f\u00fcr eigene Marketingzwecke verwenden. Dies kann auch Werbung auf Facebook einschlie\u00dfen&#8220;, hei\u00dft es auf der Homepage.<\/p>\n<div id=\"attachment_55394\" style=\"width: 710px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-55394\" class=\"size-medium wp-image-55394\" src=\"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/company-3254289_1280-700x467.jpg\" alt=\"WhatsApp neue Nutzungsbedingungen: Handy mit Account l\u00f6schen auf dem Display. Bild: Pixabay\" width=\"700\" height=\"467\" srcset=\"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/company-3254289_1280-700x467.jpg 700w, https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/company-3254289_1280-1049x700.jpg 1049w, https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/company-3254289_1280-768x512.jpg 768w, https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/company-3254289_1280.jpg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-55394\" class=\"wp-caption-text\">Wollen Sie den Nutzungsbedingungen nicht zustimmen, k\u00f6nnen Sie alternative Messenger verwenden und den WhatsApp-Account l\u00f6schen. Bild: Pixabay<\/p><\/div>\n<h3 id=\"sechs\">WhatsApp neue Nutzungsbedingungen ablehnen<\/h3>\n<p>Es ist also nur eine Frage der Zeit, bis auf WhatsApp neue Nutzungsbedingungen durchgesetzt werden. Wenn Sie WhatsApp k\u00fcnftig weiter uneingeschr\u00e4nkt nutzen m\u00f6chten, wird Ihnen auf Dauer nichts anderes \u00fcbrig bleiben, als den neuen Nutzungsbedingungen\u00a0 zuzustimmen. Doch bis es soweit ist, k\u00f6nnen Sie die Sache entspannt aussitzen. <strong>Einschr\u00e4nkungen<\/strong> wird es erst einmal <strong>nicht geben<\/strong>, wenn Sie die Zustimmung verweigern.<\/p>\n<p>Und wenn Sie bis dahin immer noch der Meinung sind, den <strong>Nutzungsbedingungen nicht zustimmen<\/strong> zu k\u00f6nnen oder wollen, weil Sie die <strong>Datenweitergabe verhindern<\/strong> m\u00f6chten, dann bleibt Ihnen immer noch der Weg, einen <strong>anderen Messenger<\/strong> zu nutzen. Ob <a href=\"https:\/\/pcspezialist.de\/blog\/2020\/06\/09\/signal-messenger\/\">Signal<\/a> (<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=org.thoughtcrime.securesms&amp;hl=de&amp;gl=US\" target=\"_blank\" rel=\"noopener noreferrer\">Android<\/a>\/<a href=\"https:\/\/apps.apple.com\/de\/app\/signal-sicherer-messenger\/id874139669\" target=\"_blank\" rel=\"noopener noreferrer\">iOS<\/a>), <a href=\"https:\/\/pcspezialist.de\/blog\/2015\/06\/22\/whatsapp-alternative-threema-verschluesseltes-messaging-fuer-android-und-ios\/\">Threema<\/a> (<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=ch.threema.app&amp;hl=de&amp;gl=US\" target=\"_blank\" rel=\"noopener noreferrer\">Android<\/a>\/<a href=\"https:\/\/apps.apple.com\/de\/app\/threema-sicherer-messenger\/id578665578\" target=\"_blank\" rel=\"noopener noreferrer\">iOS<\/a>) oder <a href=\"https:\/\/pcspezialist.de\/blog\/2021\/01\/18\/telegram-messenger\/\">Telegram<\/a> (<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=org.telegram.messenger&amp;hl=de&amp;gl=US\" target=\"_blank\" rel=\"noopener noreferrer\">Android<\/a>\/<a href=\"https:\/\/apps.apple.com\/de\/app\/telegram-messenger\/id686449807\" target=\"_blank\" rel=\"noopener noreferrer\">iOS<\/a>), es gibt eine gro\u00dfe Auswahl. Es stellt sich nur die Frage, wo man die meisten Kontakte hat. Wollen Sie WhatsApp komplett den R\u00fccken kehren, erfahren Sie bei uns, wie Sie Ihren <a href=\"https:\/\/pcspezialist.de\/blog\/2019\/08\/21\/whatsapp-account-loeschen\/\">WhatsApp-Account korrekt l\u00f6schen<\/a>.<\/p>\n<p>Wie ist Ihre Meinung zu den neuen Datenschutz- und Nutzungsbedingungen auf WhatsApp? Teilen Sie uns gern Ihre Ansicht in unseren Kommentaren mit.<\/p>\n<h3 id=\"sieben\">Update vom 01.06.2021: Erneute Rolle r\u00fcckw\u00e4rts<\/h3>\n<p>Neue Woche neue Nachricht von WhatsApp! Immer noch verweigern zahlreiche Nutzer die Zustimmung zu den am <strong>15. Mai<\/strong> in Kraft getretenen <strong>Nutzungsbedingungen<\/strong>. Zun\u00e4chst hie\u00df es ja, dass Verweigerer nur noch 120 Tage uneingeschr\u00e4nkten Zugriff auf Ihren Account haben. erst nach dieser Zeitspanne sollte es zu Einschr\u00e4nkungen kommen.<\/p>\n<p>Doch das ist nun schon wieder <strong>hinf\u00e4llig<\/strong>. \u201eThe Next Web\u201c und \u201eThe Verge\u201c berichten \u00fcbereinstimmend, dass es mittlerweile <strong>keine Pl\u00e4ne<\/strong> mehr gibt, den <strong>Funktionsumfang von WhatsApp einzuschr\u00e4nken<\/strong>. Auch dann nicht, wenn Nutzer den neuen Nutzungsbedingungen nicht zustimmen. Das zeigt auch ein Blick auf die WhatsApp-Hilfeseiten.<\/p>\n<p>WhatsApp rudert also erneut zur\u00fcck. Doch warum? Ist die <strong>Angst vor der Konkurrenz<\/strong> so gro\u00df? Oder liegt die Ursache darin, dass zumindest deutsche Nutzerdaten f\u00fcr Facebook tabu sind? Tatsache ist n\u00e4mlich, dass es in Deutschland eine Anordnung gibt, die es Facebook untersagt, WhatsApp-Daten deutscher Nutzer zu verarbeiten.<\/p>\n<h3 id=\"acht\">Update vom 30.08.2021: Nutzungsbedingungen optional<\/h3>\n<p>Nach massiver Kritik und zahlreichen Nutzern, die WhatsApp wegen der neuen Nutzungsbedingungen den R\u00fccken kehren, gibt WhatsApp nun auf: Die <strong>neuen Nutzungsbedingungen<\/strong> sind <strong>nicht mehr verpflichtend<\/strong> f\u00fcr alle Nutzer. Mit einer Einschr\u00e4nkung: Wenn Sie per WhatsApp mit Unternehmen, die Cloud-Dienste nutzen, kommunizieren m\u00f6chten, m\u00fcssen Sie den WhatsApp-Nutzungsbedingungen zustimmen.<\/p>\n<p>Wenn Sie grunds\u00e4tzlich per Telefon oder E-Mail mit mit Unternehmen Kontakt haben und nicht \u00fcber WhatsApp mit einem Unternehmen kommunizieren, m\u00fcssen Sie die neuen Nutzungsbedingungen nicht annehmen. Den <strong>Messenger<\/strong> k\u00f6nnen Sie dennoch <strong>ganz normal und ohne Einschr\u00e4nkungen nutzen<\/strong>.<\/p>\n<p>Bislang hat WhatsApp diese Neuerung noch nicht offiziell verk\u00fcndet. Und wann das Update beim Nutzer eintrifft, ist noch nicht klar. Im Allgemeinen ist es so, dass neue Funktionen oder neuer Code einige Wochen braucht, um es in die finale Version zu schaffen.<\/p>\n<p>_______________________________________________<\/p>\n<p><small>Weiterf\u00fchrende Links: <a href=\"https:\/\/www.connect.de\/news\/whatsapp-nutzungsbedingungen-ohne-zustimmung-account-eingeschraenkt-3201477.html\" target=\"_blank\" rel=\"noopener noreferrer\">Connect<\/a>, <a href=\"https:\/\/t3n.de\/news\/whatsapp-rueckzieher-keine-ab-1377772\/\" target=\"_blank\" rel=\"noopener noreferrer\">T3N<\/a>, <a href=\"https:\/\/www.pcwelt.de\/news\/Whatsapp-will-ab-15.5.-doch-keine-Konten-loeschen-Einschraenkungen-drohen-aber-11026210.html\" target=\"_blank\" rel=\"noopener noreferrer\">PCWelt<\/a>, <a href=\"https:\/\/www.messengerpeople.com\/de\/whatsapp-agb-anpassungen-2021-was-du-wirklich-wissen-musst\/\" target=\"_blank\" rel=\"noopener noreferrer\">Messengerpeople<\/a>, <a href=\"https:\/\/www.netzwelt.de\/news\/184033-whatsapp-neuen-nutzungsbedingungen-100521.html\" target=\"_blank\" rel=\"noopener noreferrer\">Netzwelt<\/a>, <a href=\"https:\/\/www.tagesschau.de\/wirtschaft\/verbraucher\/whatsapp-messenger-facebook-datenschutz-101.html\" target=\"_blank\" rel=\"noopener noreferrer\">Tagessschau<\/a>, <a href=\"https:\/\/thenextweb.com\/news\/whatsapp-says-it-wont-limit-functionality-if-you-refuse-its-privacy-policy-for-now\" target=\"_blank\" rel=\"noopener noreferrer\">The Next Web<\/a>, <a href=\"https:\/\/www.theverge.com\/2021\/5\/28\/22458805\/whatsapp-privacy-policy-no-plans-limit-functionality?scrolla=5eb6d68b7fedc32c19ef33b4\" target=\"_blank\" rel=\"noopener noreferrer\">The Verge<\/a>, <a href=\"https:\/\/faq.whatsapp.com\/general\/security-and-privacy\/what-happens-when-our-terms-and-privacy-policy-updates-take-effect\" target=\"_blank\" rel=\"noopener noreferrer\">WhatsApp FAQs<\/a>, <a href=\"https:\/\/wabetainfo.com\/news-about-terms-of-service-they-will-be-optional\/\" target=\"_blank\" rel=\"noopener\">WABetainfo<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bereits im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt und Nutzer per Pop-up darum gebeten, dass sie den Nutzungsbedingungen 2021 zustimmen. Ziel der neuen Nutzungsbedingungen ist es, dass WhatsApp bestimmte Daten mit Facebook-Unternehmen und Facebook-Dienstleistern teilen kann.\u00a0 Was passiert, wenn man den Nutzungsbedingungen nicht zustimmt hat? Alle Infos dazu bei uns.<\/p>\n","protected":false},"author":98,"featured_media":55396,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6913],"tags":[2192,3764],"class_list":["post-55369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verschiedenes","tag-messenger","tag-whatsapp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WhatsApp neue Nutzungsbedingungen gelten seit Samstag<\/title>\n<meta name=\"description\" content=\"Im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt \u2013 und die Einf\u00fchrung im Februar auf Mai verschoben. Und nun? Alle Infos hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WhatsApp neue Nutzungsbedingungen gelten seit Samstag\" \/>\n<meta property=\"og:description\" content=\"Im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt \u2013 und die Einf\u00fchrung im Februar auf Mai verschoben. Und nun? Alle Infos hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"PC-SPEZIALIST Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T08:45:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T07:46:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/girl-4682332_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maren Keller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maren Keller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/\"},\"author\":{\"name\":\"Maren Keller\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/#\\\/schema\\\/person\\\/e9cb801a8b8ea9138af26a02b8b6d14f\"},\"headline\":\"WhatsApp neue Nutzungsbedingungen ## Konzern rudert erneut zur\u00fcck: keine Accountl\u00f6schung\",\"datePublished\":\"2021-05-17T08:45:35+00:00\",\"dateModified\":\"2024-11-05T07:46:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/\"},\"wordCount\":1448,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/girl-4682332_1920.jpg\",\"keywords\":[\"Messenger\",\"WhatsApp\"],\"articleSection\":[\"Verschiedenes\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/\",\"url\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/\",\"name\":\"WhatsApp neue Nutzungsbedingungen gelten seit Samstag\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/girl-4682332_1920.jpg\",\"datePublished\":\"2021-05-17T08:45:35+00:00\",\"dateModified\":\"2024-11-05T07:46:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/#\\\/schema\\\/person\\\/e9cb801a8b8ea9138af26a02b8b6d14f\"},\"description\":\"Im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt \u2013 und die Einf\u00fchrung im Februar auf Mai verschoben. Und nun? Alle Infos hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/girl-4682332_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/girl-4682332_1920.jpg\",\"width\":1920,\"height\":1314,\"caption\":\"Ein junges M\u00e4dchen tippt WhatsApp-Nachrichten. Ob sie den neuen Nutzungsbedingungen zugestimmt hat? Bild: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/2021\\\/05\\\/17\\\/whatsapp-neue-nutzungsbedingungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WhatsApp neue Nutzungsbedingungen ## Konzern rudert erneut zur\u00fcck: keine Accountl\u00f6schung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/\",\"name\":\"PC-SPEZIALIST Blog\",\"description\":\"IT-Service, Trends &amp; Technik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/#\\\/schema\\\/person\\\/e9cb801a8b8ea9138af26a02b8b6d14f\",\"name\":\"Maren Keller\",\"description\":\"PC-SPEZIALIST ist eine Marke der in Schlo\u00df Holte ans\u00e4ssigen SYNAXON. Seit 2016 arbeitet Maren Keller f\u00fcr den PC-SPEZIALIST-Blog. Gestartet als Online-Redakteurin ist sie mittlerweile Content Marketing Managerin und tr\u00e4gt unter anderem die Verantwortung f\u00fcr die Inhalte des Blogs. In den Jahren 2017 und 2020 hat sie parallel f\u00fcr den Blog des IT-SERVICE.NETWORK geschrieben. Die studierte Germanistin und Politologin hat einen Sp\u00fcrsinn f\u00fcr aktuelle Bedrohungen im IT-Bereich entwickelt und versteht es, das Fachwissen von PC-SPEZIALIST dem Leser verst\u00e4ndlich darzubieten. Nicht zu verleugnen ist allerdings ihre Ungeduld, die sich in flinken Fingern auf der Tastatur zeigt und gleichzeitig f\u00fcr einen hohen Output sorgt. Ihre journalistische Karriere begann Maren Keller Mitte der 1990er Jahre mit dem Verfassen von Sportberichten f\u00fcr die Regionalseiten ihrer Heimatzeitung in Bremerhaven. Nach dem Studium in Hannover, das von zahlreichen Praktika bei Funk, Fernsehen und Zeitung begleitet wurde, kehrte sie f\u00fcr ein journalistisches Volontariat in ihre Heimat zur\u00fcck, um bei der NORDSEE-ZEITUNG den Beruf des Redakteurs von der Pike auf zu lernen und anschlie\u00dfend in der Sportredaktion zu arbeiten. W\u00e4hrend ihrer Elternzeiten und beruflich bedingten Umz\u00fcgen arbeitete sie als freie Journalistin f\u00fcr verschiedene Tageszeitungen und fand 2016 den Weg zur SYNAXON, wo sie heute als Content Marketing Managerin in Lohn und Brot steht. In ihrer Freizeit zeigt sie ihr Talent f\u00fcr\u2019s Schreiben nicht. Stattdessen liegen ihre Schwerpunkt dort im Bereich Haus, Familie, Garten und Hund. Au\u00dferdem ist sie musikalisch unterwegs, bl\u00e4st das Jagdhorn in einem Bl\u00e4serkorps, spielt Klavier und singt im Chor. Sie haben Fragen an Maren Keller? Sie erreichen sie per E-Mail an redaktion@pcspezialist.de\",\"url\":\"https:\\\/\\\/pcspezialist.de\\\/blog\\\/author\\\/maren\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WhatsApp neue Nutzungsbedingungen gelten seit Samstag","description":"Im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt \u2013 und die Einf\u00fchrung im Februar auf Mai verschoben. Und nun? Alle Infos hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/","og_locale":"de_DE","og_type":"article","og_title":"WhatsApp neue Nutzungsbedingungen gelten seit Samstag","og_description":"Im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt \u2013 und die Einf\u00fchrung im Februar auf Mai verschoben. Und nun? Alle Infos hier.","og_url":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/","og_site_name":"PC-SPEZIALIST Blog","article_published_time":"2021-05-17T08:45:35+00:00","article_modified_time":"2024-11-05T07:46:22+00:00","og_image":[{"width":1920,"height":1314,"url":"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/girl-4682332_1920.jpg","type":"image\/jpeg"}],"author":"Maren Keller","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Maren Keller","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#article","isPartOf":{"@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/"},"author":{"name":"Maren Keller","@id":"https:\/\/pcspezialist.de\/blog\/#\/schema\/person\/e9cb801a8b8ea9138af26a02b8b6d14f"},"headline":"WhatsApp neue Nutzungsbedingungen ## Konzern rudert erneut zur\u00fcck: keine Accountl\u00f6schung","datePublished":"2021-05-17T08:45:35+00:00","dateModified":"2024-11-05T07:46:22+00:00","mainEntityOfPage":{"@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/"},"wordCount":1448,"commentCount":0,"image":{"@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#primaryimage"},"thumbnailUrl":"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/girl-4682332_1920.jpg","keywords":["Messenger","WhatsApp"],"articleSection":["Verschiedenes"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/","url":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/","name":"WhatsApp neue Nutzungsbedingungen gelten seit Samstag","isPartOf":{"@id":"https:\/\/pcspezialist.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#primaryimage"},"image":{"@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#primaryimage"},"thumbnailUrl":"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/girl-4682332_1920.jpg","datePublished":"2021-05-17T08:45:35+00:00","dateModified":"2024-11-05T07:46:22+00:00","author":{"@id":"https:\/\/pcspezialist.de\/blog\/#\/schema\/person\/e9cb801a8b8ea9138af26a02b8b6d14f"},"description":"Im Januar hatte WhatsApp neue Nutzungsbedingungen angek\u00fcndigt \u2013 und die Einf\u00fchrung im Februar auf Mai verschoben. Und nun? Alle Infos hier.","breadcrumb":{"@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#primaryimage","url":"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/girl-4682332_1920.jpg","contentUrl":"https:\/\/pcspezialist.de\/blog\/wp-content\/uploads\/2021\/05\/girl-4682332_1920.jpg","width":1920,"height":1314,"caption":"Ein junges M\u00e4dchen tippt WhatsApp-Nachrichten. Ob sie den neuen Nutzungsbedingungen zugestimmt hat? Bild: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/pcspezialist.de\/blog\/2021\/05\/17\/whatsapp-neue-nutzungsbedingungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/pcspezialist.de\/blog\/"},{"@type":"ListItem","position":2,"name":"WhatsApp neue Nutzungsbedingungen ## Konzern rudert erneut zur\u00fcck: keine Accountl\u00f6schung"}]},{"@type":"WebSite","@id":"https:\/\/pcspezialist.de\/blog\/#website","url":"https:\/\/pcspezialist.de\/blog\/","name":"PC-SPEZIALIST Blog","description":"IT-Service, Trends &amp; Technik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pcspezialist.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/pcspezialist.de\/blog\/#\/schema\/person\/e9cb801a8b8ea9138af26a02b8b6d14f","name":"Maren Keller","description":"PC-SPEZIALIST ist eine Marke der in Schlo\u00df Holte ans\u00e4ssigen SYNAXON. Seit 2016 arbeitet Maren Keller f\u00fcr den PC-SPEZIALIST-Blog. Gestartet als Online-Redakteurin ist sie mittlerweile Content Marketing Managerin und tr\u00e4gt unter anderem die Verantwortung f\u00fcr die Inhalte des Blogs. In den Jahren 2017 und 2020 hat sie parallel f\u00fcr den Blog des IT-SERVICE.NETWORK geschrieben. Die studierte Germanistin und Politologin hat einen Sp\u00fcrsinn f\u00fcr aktuelle Bedrohungen im IT-Bereich entwickelt und versteht es, das Fachwissen von PC-SPEZIALIST dem Leser verst\u00e4ndlich darzubieten. Nicht zu verleugnen ist allerdings ihre Ungeduld, die sich in flinken Fingern auf der Tastatur zeigt und gleichzeitig f\u00fcr einen hohen Output sorgt. Ihre journalistische Karriere begann Maren Keller Mitte der 1990er Jahre mit dem Verfassen von Sportberichten f\u00fcr die Regionalseiten ihrer Heimatzeitung in Bremerhaven. Nach dem Studium in Hannover, das von zahlreichen Praktika bei Funk, Fernsehen und Zeitung begleitet wurde, kehrte sie f\u00fcr ein journalistisches Volontariat in ihre Heimat zur\u00fcck, um bei der NORDSEE-ZEITUNG den Beruf des Redakteurs von der Pike auf zu lernen und anschlie\u00dfend in der Sportredaktion zu arbeiten. W\u00e4hrend ihrer Elternzeiten und beruflich bedingten Umz\u00fcgen arbeitete sie als freie Journalistin f\u00fcr verschiedene Tageszeitungen und fand 2016 den Weg zur SYNAXON, wo sie heute als Content Marketing Managerin in Lohn und Brot steht. In ihrer Freizeit zeigt sie ihr Talent f\u00fcr\u2019s Schreiben nicht. Stattdessen liegen ihre Schwerpunkt dort im Bereich Haus, Familie, Garten und Hund. Au\u00dferdem ist sie musikalisch unterwegs, bl\u00e4st das Jagdhorn in einem Bl\u00e4serkorps, spielt Klavier und singt im Chor. Sie haben Fragen an Maren Keller? Sie erreichen sie per E-Mail an redaktion@pcspezialist.de","url":"https:\/\/pcspezialist.de\/blog\/author\/maren\/"}]}},"_links":{"self":[{"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/posts\/55369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/comments?post=55369"}],"version-history":[{"count":23,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/posts\/55369\/revisions"}],"predecessor-version":[{"id":67013,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/posts\/55369\/revisions\/67013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/media\/55396"}],"wp:attachment":[{"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/media?parent=55369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/categories?post=55369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pcspezialist.de\/blog\/wp-json\/wp\/v2\/tags?post=55369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}